{"id":3,"date":"2023-06-25T11:54:29","date_gmt":"2023-06-25T09:54:29","guid":{"rendered":"http:\/\/histoire-et-resumes.com\/?page_id=3"},"modified":"2024-04-04T11:29:03","modified_gmt":"2024-04-04T09:29:03","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"\r\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/#Qui_suis-je\" >Qui suis-je ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/#Commentaires\" >Commentaires<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/#Medias\" >M\u00e9dias<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/#Cookies\" >Cookies<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/#Contenu_embarque_depuis_dautres_sites\" >Contenu embarqu\u00e9 depuis d\u2019autres sites<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/#Durees_de_stockage_de_vos_donnees\" >Dur\u00e9es de stockage de vos donn\u00e9es<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/#Les_droits_que_vous_avez_sur_vos_donnees\" >Les droits que vous avez sur vos donn\u00e9es<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/#Transmission_de_vos_donnees_personnelles\" >Transmission de vos donn\u00e9es personnelles<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Qui_suis-je\"><\/span><strong>Qui suis-je ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Je suis un internaute passionn\u00e9 par l\u2019Histoire ainsi que par pleins d\u2019autres sujets. Pour en savoir plus, je vous invite \u00e0 consulter mon site officiel :\u00a0\u00a0<a href=\"https:\/\/misterfanjo.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/misterfanjo.com\/<\/a><\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Commentaires\"><\/span><strong>Commentaires<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Quand vous laissez un commentaire sur notre site, les donn\u00e9es inscrites dans le formulaire de commentaire, ainsi que votre adresse IP et l\u2019agent utilisateur de votre navigateur sont collect\u00e9s pour nous aider \u00e0 la d\u00e9tection des commentaires ind\u00e9sirables.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Une cha\u00eene anonymis\u00e9e cr\u00e9\u00e9e \u00e0 partir de votre adresse e-mail (\u00e9galement appel\u00e9e hash) peut \u00eatre envoy\u00e9e au service Gravatar pour v\u00e9rifier si vous utilisez ce dernier. Les clauses de confidentialit\u00e9 du service Gravatar sont disponibles ici\u00a0: https:\/\/automattic.com\/privacy\/. Apr\u00e8s validation de votre commentaire, votre photo de profil sera visible publiquement \u00e0 cot\u00e9 de votre commentaire.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Medias\"><\/span><strong>M\u00e9dias<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si vous t\u00e9l\u00e9versez des images sur le site, nous vous conseillons d\u2019\u00e9viter de t\u00e9l\u00e9verser des images contenant des donn\u00e9es EXIF de coordonn\u00e9es GPS. Les personnes visitant votre site peuvent t\u00e9l\u00e9charger et extraire des donn\u00e9es de localisation depuis ces images.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Cookies\"><\/span><strong>Cookies<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si vous d\u00e9posez un commentaire sur notre site, il vous sera propos\u00e9 d\u2019enregistrer votre nom, adresse e-mail et site dans des cookies. C\u2019est uniquement pour votre confort afin de ne pas avoir \u00e0 saisir ces informations si vous d\u00e9posez un autre commentaire plus tard. Ces cookies expirent au bout d\u2019un an.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si vous vous rendez sur la page de connexion, un cookie temporaire sera cr\u00e9\u00e9 afin de d\u00e9terminer si votre navigateur accepte les cookies. Il ne contient pas de donn\u00e9es personnelles et sera supprim\u00e9 automatiquement \u00e0 la fermeture de votre navigateur.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Lorsque vous vous connecterez, nous mettrons en place un certain nombre de cookies pour enregistrer vos informations de connexion et vos pr\u00e9f\u00e9rences d\u2019\u00e9cran. La dur\u00e9e de vie d\u2019un cookie de connexion est de deux jours, celle d\u2019un cookie d\u2019option d\u2019\u00e9cran est d\u2019un an. Si vous cochez \u00ab\u00a0Se souvenir de moi\u00a0\u00bb, votre cookie de connexion sera conserv\u00e9 pendant deux semaines. Si vous vous d\u00e9connectez de votre compte, le cookie de connexion sera effac\u00e9.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">En modifiant ou en publiant une publication, un cookie suppl\u00e9mentaire sera enregistr\u00e9 dans votre navigateur. Ce cookie ne comprend aucune donn\u00e9e personnelle. Il indique simplement l\u2019ID de la publication que vous venez de modifier. Il expire au bout d\u2019un jour.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Contenu_embarque_depuis_dautres_sites\"><\/span><strong>Contenu embarqu\u00e9 depuis d\u2019autres sites<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Les articles de ce site peuvent inclure des contenus int\u00e9gr\u00e9s (par exemple des vid\u00e9os, images, articles\u2026). Le contenu int\u00e9gr\u00e9 depuis d\u2019autres sites se comporte de la m\u00eame mani\u00e8re que si le visiteur se rendait sur cet autre site.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Ces sites web pourraient collecter des donn\u00e9es sur vous, utiliser des cookies, embarquer des outils de suivis tiers, suivre vos interactions avec ces contenus embarqu\u00e9s si vous disposez d\u2019un compte connect\u00e9 sur leur site web.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Durees_de_stockage_de_vos_donnees\"><\/span><strong>Dur\u00e9es de stockage de vos donn\u00e9es<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si vous laissez un commentaire, le commentaire et ses m\u00e9tadonn\u00e9es sont conserv\u00e9s ind\u00e9finiment. Cela permet de reconna\u00eetre et approuver automatiquement les commentaires suivants au lieu de les laisser dans la file de mod\u00e9ration.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Pour les comptes qui s\u2019inscrivent sur notre site (le cas \u00e9ch\u00e9ant), nous stockons \u00e9galement les donn\u00e9es personnelles indiqu\u00e9es dans leur profil. Tous les comptes peuvent voir, modifier ou supprimer leurs informations personnelles \u00e0 tout moment (\u00e0 l\u2019exception de leur identifiant). Les gestionnaires du site peuvent aussi voir et modifier ces informations.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Les_droits_que_vous_avez_sur_vos_donnees\"><\/span><strong>Les droits que vous avez sur vos donn\u00e9es<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si vous avez un compte ou si vous avez laiss\u00e9 des commentaires sur le site, vous pouvez demander \u00e0 recevoir un fichier contenant toutes les donn\u00e9es personnelles que nous poss\u00e9dons \u00e0 votre sujet, incluant celles que vous nous avez fournies. Vous pouvez \u00e9galement demander la suppression des donn\u00e9es personnelles vous concernant. Cela ne prend pas en compte les donn\u00e9es stock\u00e9es \u00e0 des fins administratives, l\u00e9gales ou pour des raisons de s\u00e9curit\u00e9.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Transmission_de_vos_donnees_personnelles\"><\/span><strong>Transmission de vos donn\u00e9es personnelles<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Les commentaires des visiteurs peuvent \u00eatre v\u00e9rifi\u00e9s \u00e0 l\u2019aide d\u2019un service automatis\u00e9 de d\u00e9tection des commentaires ind\u00e9sirables.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Qui suis-je ? Je suis un internaute passionn\u00e9 par l\u2019Histoire ainsi que par pleins d\u2019autres sujets. Pour en savoir plus, je vous invite \u00e0 consulter mon site officiel :\u00a0\u00a0https:\/\/misterfanjo.com\/ Commentaires Quand vous laissez un commentaire sur notre site, les donn\u00e9es inscrites dans le formulaire de commentaire, ainsi que votre adresse IP et l\u2019agent utilisateur de votre navigateur sont collect\u00e9s pour nous aider \u00e0 la d\u00e9tection des commentaires ind\u00e9sirables. Une cha\u00eene anonymis\u00e9e cr\u00e9\u00e9e \u00e0 partir de votre adresse e-mail (\u00e9galement appel\u00e9e hash) peut \u00eatre envoy\u00e9e au service Gravatar pour v\u00e9rifier si vous utilisez ce dernier. Les clauses de confidentialit\u00e9 du service Gravatar sont disponibles ici\u00a0: https:\/\/automattic.com\/privacy\/. Apr\u00e8s validation de votre commentaire, votre photo de profil sera visible publiquement \u00e0 cot\u00e9 de votre commentaire. M\u00e9dias Si vous t\u00e9l\u00e9versez des images sur le site, nous vous conseillons d\u2019\u00e9viter de t\u00e9l\u00e9verser des images contenant des donn\u00e9es EXIF de coordonn\u00e9es GPS. Les personnes visitant votre site peuvent t\u00e9l\u00e9charger et extraire des donn\u00e9es de localisation depuis ces images. Cookies Si vous d\u00e9posez un commentaire sur notre site, il vous sera propos\u00e9 d\u2019enregistrer votre nom, adresse e-mail et site dans des cookies. C\u2019est uniquement pour votre confort afin de ne pas avoir \u00e0 saisir ces informations si vous d\u00e9posez un autre commentaire plus tard. Ces cookies expirent au bout d\u2019un an. Si vous vous rendez sur la page de connexion, un cookie temporaire sera cr\u00e9\u00e9 afin de d\u00e9terminer si votre navigateur accepte les cookies. Il ne contient pas de donn\u00e9es personnelles et sera supprim\u00e9 automatiquement \u00e0 la fermeture de votre navigateur. Lorsque vous vous connecterez, nous mettrons en place un certain nombre de cookies pour enregistrer vos informations de connexion et vos pr\u00e9f\u00e9rences d\u2019\u00e9cran. La dur\u00e9e de vie d\u2019un cookie de connexion est de deux jours, celle d\u2019un cookie d\u2019option d\u2019\u00e9cran est d\u2019un an. Si vous cochez \u00ab\u00a0Se souvenir de moi\u00a0\u00bb, votre cookie de connexion sera conserv\u00e9 pendant deux semaines. Si vous vous d\u00e9connectez de votre compte, le cookie de connexion sera effac\u00e9. En modifiant ou en publiant une publication, un cookie suppl\u00e9mentaire sera enregistr\u00e9 dans votre navigateur. Ce cookie ne comprend aucune donn\u00e9e personnelle. Il indique simplement l\u2019ID de la publication que vous venez de modifier. Il expire au bout d\u2019un jour. Contenu embarqu\u00e9 depuis d\u2019autres sites Les articles de ce site peuvent inclure des contenus int\u00e9gr\u00e9s (par exemple des vid\u00e9os, images, articles\u2026). Le contenu int\u00e9gr\u00e9 depuis d\u2019autres sites se comporte de la m\u00eame mani\u00e8re que si le visiteur se rendait sur cet autre site. Ces sites web pourraient collecter des donn\u00e9es sur vous, utiliser des cookies, embarquer des outils de suivis tiers, suivre vos interactions avec ces contenus embarqu\u00e9s si vous disposez d\u2019un compte connect\u00e9 sur leur site web. Dur\u00e9es de stockage de vos donn\u00e9es Si vous laissez un commentaire, le commentaire et ses m\u00e9tadonn\u00e9es sont conserv\u00e9s ind\u00e9finiment. Cela permet de reconna\u00eetre et approuver automatiquement les commentaires suivants au lieu de les laisser dans la file de mod\u00e9ration. Pour les comptes qui s\u2019inscrivent sur notre site (le cas \u00e9ch\u00e9ant), nous stockons \u00e9galement les donn\u00e9es personnelles indiqu\u00e9es dans leur profil. Tous les comptes peuvent voir, modifier ou supprimer leurs informations personnelles \u00e0 tout moment (\u00e0 l\u2019exception de leur identifiant). Les gestionnaires du site peuvent aussi voir et modifier ces informations. Les droits que vous avez sur vos donn\u00e9es Si vous avez un compte ou si vous avez laiss\u00e9 des commentaires sur le site, vous pouvez demander \u00e0 recevoir un fichier contenant toutes les donn\u00e9es personnelles que nous poss\u00e9dons \u00e0 votre sujet, incluant celles que vous nous avez fournies. Vous pouvez \u00e9galement demander la suppression des donn\u00e9es personnelles vous concernant. Cela ne prend pas en compte les donn\u00e9es stock\u00e9es \u00e0 des fins administratives, l\u00e9gales ou pour des raisons de s\u00e9curit\u00e9. Transmission de vos donn\u00e9es personnelles Les commentaires des visiteurs peuvent \u00eatre v\u00e9rifi\u00e9s \u00e0 l\u2019aide d\u2019un service automatis\u00e9 de d\u00e9tection des commentaires ind\u00e9sirables.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":103,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de confidentialit\u00e9 - R\u00e9sum\u00e9 de l&#039;Histoire<\/title>\n<meta name=\"description\" content=\"\u27bd Cliquez ici pour d\u00e9couvrir la politique de confidentialit\u00e9 du projet sur le r\u00e9sum\u00e9 de l&#039;Histoire. C\u2019est parti \u2705\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 - R\u00e9sum\u00e9 de l&#039;Histoire\" \/>\n<meta property=\"og:description\" content=\"\u27bd Cliquez ici pour d\u00e9couvrir la politique de confidentialit\u00e9 du projet sur le r\u00e9sum\u00e9 de l&#039;Histoire. C\u2019est parti \u2705\" \/>\n<meta property=\"og:url\" content=\"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9sum\u00e9 de l&#039;Histoire\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-04T09:29:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@misterfanjo\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/histoire-et-resumes.com\\\/index.php\\\/le-resume-de-lhistoire\\\/infos-generales\\\/politique-de-confidentialite\\\/\",\"url\":\"https:\\\/\\\/histoire-et-resumes.com\\\/index.php\\\/le-resume-de-lhistoire\\\/infos-generales\\\/politique-de-confidentialite\\\/\",\"name\":\"Politique de confidentialit\u00e9 - R\u00e9sum\u00e9 de l&#039;Histoire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/histoire-et-resumes.com\\\/#website\"},\"datePublished\":\"2023-06-25T09:54:29+00:00\",\"dateModified\":\"2024-04-04T09:29:03+00:00\",\"description\":\"\u27bd Cliquez ici pour d\u00e9couvrir la politique de confidentialit\u00e9 du projet sur le r\u00e9sum\u00e9 de l'Histoire. C\u2019est parti \u2705\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/histoire-et-resumes.com\\\/index.php\\\/le-resume-de-lhistoire\\\/infos-generales\\\/politique-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/histoire-et-resumes.com\\\/index.php\\\/le-resume-de-lhistoire\\\/infos-generales\\\/politique-de-confidentialite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/histoire-et-resumes.com\\\/index.php\\\/le-resume-de-lhistoire\\\/infos-generales\\\/politique-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/histoire-et-resumes.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le r\u00e9sum\u00e9 de l&rsquo;Histoire\",\"item\":\"https:\\\/\\\/histoire-et-resumes.com\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Infos g\u00e9n\u00e9rales\",\"item\":\"https:\\\/\\\/histoire-et-resumes.com\\\/index.php\\\/le-resume-de-lhistoire\\\/infos-generales\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Politique de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/histoire-et-resumes.com\\\/#website\",\"url\":\"https:\\\/\\\/histoire-et-resumes.com\\\/\",\"name\":\"L'Histoire en un coup d'\u0153il\",\"description\":\"Un r\u00e9sum\u00e9 des 5 grandes p\u00e9riodes historiques.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/histoire-et-resumes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de confidentialit\u00e9 - R\u00e9sum\u00e9 de l&#039;Histoire","description":"\u27bd Cliquez ici pour d\u00e9couvrir la politique de confidentialit\u00e9 du projet sur le r\u00e9sum\u00e9 de l'Histoire. C\u2019est parti \u2705","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique de confidentialit\u00e9 - R\u00e9sum\u00e9 de l&#039;Histoire","og_description":"\u27bd Cliquez ici pour d\u00e9couvrir la politique de confidentialit\u00e9 du projet sur le r\u00e9sum\u00e9 de l'Histoire. C\u2019est parti \u2705","og_url":"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/","og_site_name":"R\u00e9sum\u00e9 de l&#039;Histoire","article_modified_time":"2024-04-04T09:29:03+00:00","twitter_card":"summary_large_image","twitter_site":"@misterfanjo","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/","url":"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/","name":"Politique de confidentialit\u00e9 - R\u00e9sum\u00e9 de l&#039;Histoire","isPartOf":{"@id":"https:\/\/histoire-et-resumes.com\/#website"},"datePublished":"2023-06-25T09:54:29+00:00","dateModified":"2024-04-04T09:29:03+00:00","description":"\u27bd Cliquez ici pour d\u00e9couvrir la politique de confidentialit\u00e9 du projet sur le r\u00e9sum\u00e9 de l'Histoire. C\u2019est parti \u2705","breadcrumb":{"@id":"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/politique-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/histoire-et-resumes.com\/"},{"@type":"ListItem","position":2,"name":"Le r\u00e9sum\u00e9 de l&rsquo;Histoire","item":"https:\/\/histoire-et-resumes.com\/"},{"@type":"ListItem","position":3,"name":"Infos g\u00e9n\u00e9rales","item":"https:\/\/histoire-et-resumes.com\/index.php\/le-resume-de-lhistoire\/infos-generales\/"},{"@type":"ListItem","position":4,"name":"Politique de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/histoire-et-resumes.com\/#website","url":"https:\/\/histoire-et-resumes.com\/","name":"L'Histoire en un coup d'\u0153il","description":"Un r\u00e9sum\u00e9 des 5 grandes p\u00e9riodes historiques.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/histoire-et-resumes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/histoire-et-resumes.com\/index.php\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/histoire-et-resumes.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/histoire-et-resumes.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/histoire-et-resumes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/histoire-et-resumes.com\/index.php\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":7,"href":"https:\/\/histoire-et-resumes.com\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":526,"href":"https:\/\/histoire-et-resumes.com\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions\/526"}],"up":[{"embeddable":true,"href":"https:\/\/histoire-et-resumes.com\/index.php\/wp-json\/wp\/v2\/pages\/103"}],"wp:attachment":[{"href":"https:\/\/histoire-et-resumes.com\/index.php\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}